{"id":26,"date":"2005-03-06T22:38:33","date_gmt":"2005-03-06T22:38:33","guid":{"rendered":"\/wordpress\/?p=26"},"modified":"2005-03-06T22:38:33","modified_gmt":"2005-03-06T22:38:33","slug":"23-au-secour","status":"publish","type":"post","link":"https:\/\/mrtaz.net\/wordpress\/2005\/03\/06\/23-au-secour\/","title":{"rendered":"Au secour!"},"content":{"rendered":"<p>Depuis, que je suis seul(Ouin!)<br \/>\n J&rsquo;ai la vague impression de me noyer&#8230;<\/p>\n<p> <img decoding=\"async\" src=\"\/wordpress\/dc-backup\/images\/alaide[1].gif\" alt=\"Bras agit\u00e9 sortant de l'eau...\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis, que je suis seul(Ouin!) J&rsquo;ai la vague impression de me noyer&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-26","post","type-post","status-publish","format-standard","hentry","category-la-vie-la-vraie"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7qSCz-q","jetpack-related-posts":[{"id":351,"url":"https:\/\/mrtaz.net\/wordpress\/2016\/08\/16\/onion\/","url_meta":{"origin":26,"position":0},"title":"Onion","author":"MrTAZ","date":"16\/08\/2016","format":false,"excerpt":"Je suis en passe de changer d'abonnement Internet car SFR\/Num\u00e9ricable est incapable de maintenir leur r\u00e9seau FTTLA. J'ai des coupures r\u00e9guli\u00e8res et al\u00e9atoires que je signale \u00e0 chaque fois depuis des mois mais rien ne change. Donc, pour avoir des d\u00e9bits similaires, j'ai opt\u00e9 pour un routeur 4G Huawei qui\u2026","rel":"","context":"Dans &quot;La vie, la vraie...&quot;","block_context":{"text":"La vie, la vraie...","link":"https:\/\/mrtaz.net\/wordpress\/category\/la-vie-la-vraie\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":165,"url":"https:\/\/mrtaz.net\/wordpress\/2008\/12\/08\/177-pirelli-dp-l10-hack\/","url_meta":{"origin":26,"position":1},"title":"Pirelli DP-L10 Hack","author":"MrTAZ","date":"08\/12\/2008","format":false,"excerpt":"ih ih ih Ce Week-end, j'ai retrouv\u00e9 mon t\u00e9l\u00e9phone free alias \"Black\". (Pirelli DP-L10) Alors je me suis amus\u00e9 avec! J'ai pu le flasher en version 99d et meme le r\u00e9parrer apr\u00e8s un flash mal termin\u00e9! Je vais maintenant essayer de le tweaker!!! :-D Il a 2 flash : La\u2026","rel":"","context":"Dans &quot;La vie, la vraie...&quot;","block_context":{"text":"La vie, la vraie...","link":"https:\/\/mrtaz.net\/wordpress\/category\/la-vie-la-vraie\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":43,"url":"https:\/\/mrtaz.net\/wordpress\/2005\/05\/10\/40-yop\/","url_meta":{"origin":26,"position":2},"title":"Yop!","author":"MrTAZ","date":"10\/05\/2005","format":false,"excerpt":"Je savais pas quoi \u00e9crire ces jours ci...","rel":"","context":"Dans &quot;La vie, la vraie...&quot;","block_context":{"text":"La vie, la vraie...","link":"https:\/\/mrtaz.net\/wordpress\/category\/la-vie-la-vraie\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":89,"url":"https:\/\/mrtaz.net\/wordpress\/2006\/02\/05\/86-vista\/","url_meta":{"origin":26,"position":3},"title":"Vista&#8230;","author":"MrTAZ","date":"05\/02\/2006","format":false,"excerpt":"Suite \u00e0 la lecture de l'article de pcinpact sur Windows Vista, je me suis tout de m\u00eame dit il faut voir \u00e7\u00e0... J'ai donc t\u00e9l\u00e9charg\u00e9 la build 5270 de Windows Vista. Et ensuite, avec un coll\u00e8gue de travail, nous l'avons install\u00e9. Et j'ecris juste ce petit mot pour simplement dire\u2026","rel":"","context":"Dans &quot;La vie, la vraie...&quot;","block_context":{"text":"La vie, la vraie...","link":"https:\/\/mrtaz.net\/wordpress\/category\/la-vie-la-vraie\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":90,"url":"https:\/\/mrtaz.net\/wordpress\/2006\/02\/08\/87-prefetch-de-merde\/","url_meta":{"origin":26,"position":4},"title":"Prefetch de merde!","author":"MrTAZ","date":"08\/02\/2006","format":false,"excerpt":"Et oui! apr\u00e8s 1 jour de r\u00e9fl\u00e9xion, j'ai enfin trouv\u00e9 pourquoi mon pc ne voulait plus booter... Tout d'abord, je voudrais dire a tout ceux qui ne le save pas Perfect Disk 7\u00a0: C'est de la MERDE\u00a0! !\u00a0! A ne surtout pas utiliser! Explication\u00a0: Apr\u00e8s plusieurs d\u00e9fragmentation avec SmartPlacement ou\u2026","rel":"","context":"Dans &quot;La vie, la vraie...&quot;","block_context":{"text":"La vie, la vraie...","link":"https:\/\/mrtaz.net\/wordpress\/category\/la-vie-la-vraie\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":17,"url":"https:\/\/mrtaz.net\/wordpress\/2005\/02\/24\/14-ouin\/","url_meta":{"origin":26,"position":5},"title":"Ouin!","author":"MrTAZ","date":"24\/02\/2005","format":false,"excerpt":"Il va falloir aller au boulo! C'est la vie...","rel":"","context":"Dans &quot;La vie, la vraie...&quot;","block_context":{"text":"La vie, la vraie...","link":"https:\/\/mrtaz.net\/wordpress\/category\/la-vie-la-vraie\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/mrtaz.net\/wordpress\/wp-json\/wp\/v2\/posts\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mrtaz.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mrtaz.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mrtaz.net\/wordpress\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mrtaz.net\/wordpress\/wp-json\/wp\/v2\/comments?post=26"}],"version-history":[{"count":0,"href":"https:\/\/mrtaz.net\/wordpress\/wp-json\/wp\/v2\/posts\/26\/revisions"}],"wp:attachment":[{"href":"https:\/\/mrtaz.net\/wordpress\/wp-json\/wp\/v2\/media?parent=26"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mrtaz.net\/wordpress\/wp-json\/wp\/v2\/categories?post=26"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mrtaz.net\/wordpress\/wp-json\/wp\/v2\/tags?post=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}